{"id":5821,"date":"2026-05-12T13:48:15","date_gmt":"2026-05-12T11:48:15","guid":{"rendered":"https:\/\/larbrequipousse.org\/?post_type=mec-events&#038;p=5821"},"modified":"2026-05-12T13:48:15","modified_gmt":"2026-05-12T11:48:15","slug":"domination-systemique","status":"publish","type":"mec-events","link":"https:\/\/larbrequipousse.org\/en\/events\/domination-systemique\/","title":{"rendered":"Domination syst\u00e9mique"},"content":{"rendered":"<div>Le pouvoir avec au lieu du pouvoir sur\u00a0: comprendre et sentir les dominations syst\u00e9miques pour transformer les relations entre humain.e.s<\/div>\n<div><\/div>\n<div>Comment certaines normes, institutions et habitudes reproduisent-elles des in\u00e9galit\u00e9s, m\u00eame dans des espaces qui se veulent inclusifs ou progressistes ? Pourquoi m\u00eame quand nous tentons de collaborer, retombons-nous si facilement dans des r\u00e9flexes de m\u00e9fiance et de comp\u00e9tition\u00a0?<\/div>\n<div><\/div>\n<div>Cet atelier invite \u00e0 prendre du recul sur l\u2019omnipr\u00e9sence des hi\u00e9rarchies pyramidales dans notre culture et le quotidien de nos vies, et sur sa toxicit\u00e9 en r\u00e9ponse \u00e0 nos besoins et tentatives d\u2019entraide. Au-del\u00e0 des logiques de domination syst\u00e9mique, il explorera les inspirations d\u2019autres voies explor\u00e9es par d\u2019autres cultures que la n\u00f4tre, et par le vivant autre qu\u2019humain dans son ensemble. De quoi identifier des pistes concr\u00e8tes pour transformer nos mani\u00e8res de collaborer, coexister et s\u2019\u00e9panouir ensemble.<\/div>\n<div><\/div>\n<div>\u00c0 travers rep\u00e8res th\u00e9orique et exercices r\u00e9flexifs, l\u2019objectif ne sera pas de d\u00e9signer des coupables ou de produire des r\u00e9ponses simplistes, mais bien de r\u00e9fl\u00e9chir \u00e0 des pistes pour passer du \u00ab\u00a0pouvoir sur\u00a0\u00bb au \u00ab\u00a0pouvoir avec\u00a0\u00bb et reconstruire la confiance en nos capacit\u00e9s d\u2019entraide.<\/div>\n<div><\/div>\n<div>\n<p>Gauthier Chapelle est papa, naturaliste, ing\u00e9nieur agronome et docteur en biologie polaire, auteur, conf\u00e9rencier et chercheur in-Terre-d\u00e9pendant en biomim\u00e9tisme et collapsologie. Apr\u00e8s 5 ans de sensibilisation aux changements climatiques \u00e0 la Fondation Polaire Internationale, il a \u00e9t\u00e9 un des pionniers du biomim\u00e9tisme en Europe, notamment en co-fondant l\u2019association Biomimicry-Europa (2006) et le bureau d\u2019\u00e9tudes Greenloop (2007). Depuis 2010, avec d\u2019autres co-facilitatrices.teurs de l\u2019association Terr\u2019Eveille, il propose un travail de reliance avec le vivant par le biais d\u2019ateliers de \u00ab Travail qui Relie \u00bb. Depuis 2015, il encourage un biomim\u00e9tisme organisationnel et \u00ab\u00a0low-tech\u00a0\u00bb, afin de se pr\u00e9parer aux ruptures de civilisation qu\u2019il consid\u00e8re in\u00e9vitables, aux c\u00f4t\u00e9s de ses amis et co-auteurs collapsologues Pablo Servigne (\u00ab L\u2019entraide, l\u2019autre loi de la jungle \u00bb) et Rapha\u00ebl Stevens (\u00ab Une autre fin du monde est possible \u00bb, avec Pablo Servigne).<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Le pouvoir avec au lieu du pouvoir sur\u00a0: comprendre et sentir les dominations syst\u00e9miques pour transformer les relations entre humain.e.s Comment certaines normes, institutions et habitudes reproduisent-elles des in\u00e9galit\u00e9s, m\u00eame dans des espaces qui se veulent inclusifs ou progressistes ? Pourquoi m\u00eame quand nous tentons de collaborer, retombons-nous si facilement dans des r\u00e9flexes de m\u00e9fiance et de comp\u00e9tition\u00a0? Cet atelier invite \u00e0 prendre du recul sur l\u2019omnipr\u00e9sence des hi\u00e9rarchies pyramidales dans notre culture et le quotidien de nos vies, et sur sa toxicit\u00e9 en r\u00e9ponse \u00e0 nos besoins et tentatives d\u2019entraide. Au-del\u00e0 des logiques de domination syst\u00e9mique, il explorera les inspirations d\u2019autres voies explor\u00e9es par d\u2019autres cultures que la n\u00f4tre, et par le vivant autre qu\u2019humain dans son ensemble. De quoi identifier des pistes concr\u00e8tes pour transformer nos mani\u00e8res de collaborer, coexister et s\u2019\u00e9panouir ensemble. \u00c0 travers rep\u00e8res th\u00e9orique et exercices r\u00e9flexifs, l\u2019objectif ne sera pas de d\u00e9signer des coupables ou de produire des r\u00e9ponses simplistes, mais bien de r\u00e9fl\u00e9chir \u00e0 des pistes pour passer du \u00ab\u00a0pouvoir sur\u00a0\u00bb au \u00ab\u00a0pouvoir avec\u00a0\u00bb et reconstruire la confiance en nos capacit\u00e9s d\u2019entraide. Gauthier Chapelle est papa, naturaliste, ing\u00e9nieur agronome et docteur en biologie polaire, auteur, conf\u00e9rencier et chercheur in-Terre-d\u00e9pendant en biomim\u00e9tisme et collapsologie. Apr\u00e8s 5 ans de sensibilisation aux changements climatiques \u00e0 la Fondation Polaire Internationale, il a \u00e9t\u00e9 un des pionniers du biomim\u00e9tisme en Europe, notamment en co-fondant l\u2019association Biomimicry-Europa (2006) et le bureau d\u2019\u00e9tudes Greenloop (2007). Depuis 2010, avec d\u2019autres co-facilitatrices.teurs de l\u2019association Terr\u2019Eveille, il propose un travail de reliance avec le vivant par le biais d\u2019ateliers de \u00ab Travail qui Relie \u00bb. Depuis 2015, il encourage un biomim\u00e9tisme organisationnel et \u00ab\u00a0low-tech\u00a0\u00bb, afin de se pr\u00e9parer aux ruptures de civilisation qu\u2019il consid\u00e8re in\u00e9vitables, aux c\u00f4t\u00e9s de ses amis et co-auteurs collapsologues Pablo Servigne (\u00ab L\u2019entraide, l\u2019autre loi de la jungle \u00bb) et Rapha\u00ebl Stevens (\u00ab Une autre fin du monde est possible \u00bb, avec Pablo Servigne).<\/p>","protected":false},"author":8,"featured_media":5822,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"tags":[],"mec_category":[],"class_list":["post-5821","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/larbrequipousse.org\/en\/wp-json\/wp\/v2\/mec-events\/5821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larbrequipousse.org\/en\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/larbrequipousse.org\/en\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/larbrequipousse.org\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/larbrequipousse.org\/en\/wp-json\/wp\/v2\/comments?post=5821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larbrequipousse.org\/en\/wp-json\/wp\/v2\/media\/5822"}],"wp:attachment":[{"href":"https:\/\/larbrequipousse.org\/en\/wp-json\/wp\/v2\/media?parent=5821"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larbrequipousse.org\/en\/wp-json\/wp\/v2\/tags?post=5821"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/larbrequipousse.org\/en\/wp-json\/wp\/v2\/mec_category?post=5821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}